{"id":10,"count":3,"description":"Free survey and questionnaire templates provided by eSurveysPro","link":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/tag\/survey-templates\/","name":"Survey templates","slug":"survey-templates","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/wp-json\/wp\/v2\/tags\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/wp-json\/wp\/v2\/posts?tags=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}