{"id":9,"count":5,"description":"The best online survey software tool provided by eSurveysPro","link":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/tag\/survey-software\/","name":"Survey software","slug":"survey-software","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/wp-json\/wp\/v2\/tags\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/free-questionnaire-templates.esurveyspro.com\/index.php\/wp-json\/wp\/v2\/posts?tags=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}